{"id":2254,"date":"2025-12-22T13:40:47","date_gmt":"2025-12-22T05:40:47","guid":{"rendered":"https:\/\/www.cy-package.com\/?page_id=2254"},"modified":"2025-12-22T15:49:03","modified_gmt":"2025-12-22T07:49:03","slug":"fispal-tecnologia-2025","status":"publish","type":"page","link":"https:\/\/www.cy-package.com\/ru\/fispal-tecnologia-2025\/","title":{"rendered":"FISPAL  TECNOLOGIA 2025"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2254\" class=\"elementor elementor-2254\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5dd104 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5dd104\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3aed21e7\" data-id=\"3aed21e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-841d0ca elementor-widget elementor-widget-woocommerce-breadcrumb\" data-id=\"841d0ca\" data-element_type=\"widget\" data-widget_type=\"woocommerce-breadcrumb.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav class=\"woocommerce-breadcrumb\" aria-label=\"Breadcrumb\" data-no-translation=\"\" data-trp-gettext=\"\">\u0413\u043b\u0430\u0432\u043d\u0430\u044f<\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f12c95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f12c95\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f08cd0\" data-id=\"f08cd0\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b7219cb elementor-widget elementor-widget-heading\" data-id=\"2b7219cb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FISPAL TECNOLOGIA 2025<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-798acb40 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"798acb40\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;black&#039; stroke=&#039;none&#039;%3E%3Cpath d=&#039;M12.7,2.3c-0.4-0.4-1.1-0.4-1.5,0l-8,9.1c-0.3,0.4-0.3,0.9,0,1.2l8,9.1c0.4,0.4,1.1,0.4,1.5,0l8-9.1c0.3-0.4,0.3-0.9,0-1.2L12.7,2.3z&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2cb76c24 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cb76c24\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-138f6649\" data-id=\"138f6649\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c361c8c elementor-widget elementor-widget-gallery\" data-id=\"5c361c8c\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:2,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:75,&quot;sizes&quot;:[]},&quot;aspect_ratio&quot;:&quot;4:3&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-02.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-02.jpg\" data-width=\"600\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-03.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-03.jpg\" data-width=\"600\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-04.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-04.jpg\" data-width=\"600\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-05.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-05.jpg\" data-width=\"600\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-06.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-06.jpg\" data-width=\"600\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-07.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-07.jpg\" data-width=\"600\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-11.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-11.jpg\" data-width=\"600\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-10.jpg\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/www.cy-package.com\/wp-content\/uploads\/2025\/12\/Fispal-Tecnologia-10.jpg\" data-width=\"600\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>FISPAL TECNOLOGIA 2025<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"FISPAL TECNOLOGIA 2025","_seopress_titles_desc":"CY PACK SOURCE FACTORY ATTANTED TO FISPAL  TECNOLOGIA 2025","_seopress_robots_index":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_kad_post_transparent":"","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"hide","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-2254","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.cy-package.com\/ru\/wp-json\/wp\/v2\/pages\/2254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cy-package.com\/ru\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cy-package.com\/ru\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cy-package.com\/ru\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cy-package.com\/ru\/wp-json\/wp\/v2\/comments?post=2254"}],"version-history":[{"count":8,"href":"https:\/\/www.cy-package.com\/ru\/wp-json\/wp\/v2\/pages\/2254\/revisions"}],"predecessor-version":[{"id":2279,"href":"https:\/\/www.cy-package.com\/ru\/wp-json\/wp\/v2\/pages\/2254\/revisions\/2279"}],"wp:attachment":[{"href":"https:\/\/www.cy-package.com\/ru\/wp-json\/wp\/v2\/media?parent=2254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}